{"id":522840,"date":"2022-01-07T15:00:20","date_gmt":"2022-01-07T15:00:20","guid":{"rendered":"https:\/\/droix.eu\/product\/gpd-pocket-3-kvm-rs-232-modul\/"},"modified":"2025-12-15T00:02:25","modified_gmt":"2025-12-15T00:02:25","slug":"gpd-pocket-3-kvm-rs-232-modul","status":"publish","type":"product","link":"https:\/\/stage.droix.eu\/de\/product\/gpd-pocket-3-kvm-rs-232-modul\/","title":{"rendered":"GPD Pocket 3 KVM- und RS-232-Modul"},"content":{"rendered":"<p>Der GPD Pocket 3 ist mit einem KVM-Modul ausgestattet, das eine komfortable Steuerung von Servern erm\u00f6glicht. Ebenso erm\u00f6glicht das RS232-Modul die Integration eines echten RS232-Ports, was es zu einer hervorragenden Option f\u00fcr das System-Debugging oder den Betrieb professioneller CNC-Fr\u00e4smaschinen macht.<\/p>\n<p>Beide Module sind Bestandteil des Pakets.<\/p>\n<p>Au\u00dferdem wird das GPD Pocket 3 mit einem Standard-USB-A-Modul geliefert. Bei Bedarf kann dieses Modul durch eines der beiden mitgelieferten Module ersetzt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li><strong>Offizielles GPD-Zubeh\u00f6r<\/strong><\/li>\n<li>Kombipaket mit <strong>zwei<\/strong> Erweiterungsmodulen<\/li>\n<li>Verbindung und Steuerung von Servern \u00fcber <strong>KVM<\/strong>-Modul<\/li>\n<li>Schnittstelle zu industriellen Maschinen \u00fcber <strong>RS232<\/strong><\/li>\n<\/ul>\n[cg_accordion title=\"2 Jahre Garantie auf alle GPD-Produkte\"]<\/p>\n<p>Auf alle GPD Produkte gew\u00e4hren wir 2 Jahre Garantie und bieten seit \u00fcber 13 Jahren einen zuverl\u00e4ssigen Service. Schlie\u00dfen Sie sich unserer Gemeinschaft von \u00fcber 500.000 zufriedenen Kunden an und vertrauen Sie auf Ihren Kauf. [\/cg_accordion]\n[cg_accordion title=\"Qualit\u00e4tssicherung und Tests vor der Auslieferung\"]<\/p>\n<p>Sicherstellung der Kundenzufriedenheit auf h\u00f6chstem Niveau: Jedes Ger\u00e4t wird vor der Auslieferung strengen Tests und einer mehrstufigen Qualit\u00e4tskontrolle unterzogen. Unser engagiertes Team pr\u00fcft die Leistung, Funktionalit\u00e4t und Integrit\u00e4t der Komponenten, um zu gew\u00e4hrleisten, dass Ihr GPD-Ger\u00e4t bei der Ankunft in einwandfreiem Zustand ist und Sie sich darauf verlassen k\u00f6nnen. [\/cg_accordion]\n[cg_accordion title=\"Flexible und sichere Zahlungsoptionen\"]<\/p>\n<p>Genie\u00dfen Sie den Seelenfrieden mit unserem sicheren Bezahlsystem. Wir unterst\u00fctzen alle wichtigen Zahlungsmethoden, einschlie\u00dflich Debit-\/Kreditkarten, PayPal, Apple Pay, Google Pay, Klarna, Afterpay und Affirm &#8211; und geben Ihnen die Freiheit, auf Ihre Weise zu zahlen, ob im Voraus oder in einfachen Raten. [\/cg_accordion]\n[cg_accordion title=\"Steuern\"]<\/p>\n<p>Die Preise enthalten die gesetzliche Mehrwertsteuer, die je nach Land bis zu 25 % betragen kann. Der genaue Betrag wird w\u00e4hrend des Bestellvorgangs angezeigt, um volle Transparenz zu gew\u00e4hrleisten. [\/cg_accordion]\n[cg_accordion title=\"Versand und R\u00fcckgabe\"]<\/p>\n<p>Wir arbeiten mit mehr als 10 zuverl\u00e4ssigen Versandpartnern zusammen, um sicherzustellen, dass Ihre Bestellung schnell, sicher und zuverl\u00e4ssig ankommt.<\/p>\n<p>Wir verwenden den Expressversand DDP (Delivered Duty Paid). Dies bedeutet: <\/p>\n<li>Alle Z\u00f6lle und Steuern sind bereits im angegebenen Produktpreis enthalten.<\/li>\n<li>Sie werden bei der Lieferung keine \u00fcberraschenden Kosten haben.<\/li>\n<li>In den seltenen F\u00e4llen, in denen es zu Verz\u00f6gerungen bei der Zollabfertigung kommt, wird unser Team die Abfertigung f\u00fcr Sie \u00fcbernehmen, um eine reibungslose Lieferung zu gew\u00e4hrleisten.<\/li>\n<p>Wichtige Informationen \u00fcber R\u00fccksendungen:<\/p>\n<li>Wenn Sie Ihre Bestellung zur\u00fccksenden oder eine R\u00fcckerstattung beantragen, beachten Sie bitte, dass Steuern und Z\u00f6lle, die gem\u00e4\u00df den DDP-Bedingungen in Ihrem Namen bezahlt wurden, nicht erstattet werden k\u00f6nnen.<\/li>\n<p>Ausf\u00fchrliche Informationen finden Sie in unseren <a href=\"https:\/\/stage.droix.eu\/de\/bedingungen-und-konditionen\/\" target=\"_blank\" rel=\"nofollow noopener\">Allgemeinen Gesch\u00e4ftsbedingungen<\/a>.\n<\/ul>\n<p>[\/cg_accordion]\n[cg_accordion title=\"Kundenbetreuung\"]<\/p>\n<p>Haben Sie eine Frage? Wir sind nur einen kurzen Text davon entfernt, Ihr Problem zu l\u00f6sen! [\/cg_accordion]\n[cg_accordion title=\"Das Paket enth\u00e4lt\"]<\/p>\n<ul>\n<li>1x KVM &amp; RS-232 Modul<\/li>\n<\/ul>\n<p>[\/cg_accordion]\n","protected":false},"featured_media":293623,"template":"","meta":{"_acf_changed":false},"key-features":[],"product_brand":[],"product_cat":[10573,10572],"product_tag":[],"woo-feed-brand":[],"class_list":["post-522840","product","type-product","status-publish","has-post-thumbnail","product_cat-laptop-zubehor","product_cat-zubehor","product_shipping_class-low-end","pa_brands-gpd","pa_compatibility-gpd-pocket-3","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/product\/522840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/media\/293623"}],"wp:attachment":[{"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/media?parent=522840"}],"wp:term":[{"taxonomy":"key-features","embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/key-features?post=522840"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/product_brand?post=522840"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/product_cat?post=522840"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/product_tag?post=522840"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/stage.droix.eu\/de\/wp-json\/wp\/v2\/woo-feed-brand?post=522840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}